{"id":3329,"date":"2026-04-27T19:05:23","date_gmt":"2026-04-27T18:05:23","guid":{"rendered":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/"},"modified":"2026-04-27T19:41:28","modified_gmt":"2026-04-27T18:41:28","slug":"%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv","status":"publish","type":"product","link":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/","title":{"rendered":"\u2744 Dorade royalefilet met vel 120-160g 5kg DV"},"content":{"rendered":"<p>De dorade royale of goudbrasem is een populaire kweekvis en komt voor in zowel zout als zoet water. Gekweekte dorade is een matigvette vis en meestal afkomstig uit Griekenland of Turkije.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Filet van dorade royale met huid en zonder graatje, sortering 120 tot 160g, bevroren en verpakt per doos van 5kg.<\/p>\n","protected":false},"featured_media":2247,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[169],"product_tag":[],"class_list":{"0":"post-3329","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-filet-portie","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2744 Dorade royalefilet met vel 120-160g 5kg DV - Seaco<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2744 Dorade royalefilet met vel 120-160g 5kg DV - Seaco\" \/>\n<meta property=\"og:description\" content=\"Filet van dorade royale met huid en zonder graatje, sortering 120 tot 160g, bevroren en verpakt per doos van 5kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onestep.media\/seaco\/product\/\u2744-dorade-royalefilet-met-vel-120-160g-5kg-dv\/\" \/>\n<meta property=\"og:site_name\" content=\"Seaco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T18:41:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/\",\"name\":\"\u2744 Dorade royalefilet met vel 120-160g 5kg DV - Seaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-50925ac8-292b-47a9-9760-457222ec1c82.jpg\",\"datePublished\":\"2026-04-27T18:05:23+00:00\",\"dateModified\":\"2026-04-27T18:41:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-50925ac8-292b-47a9-9760-457222ec1c82.jpg\",\"contentUrl\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-50925ac8-292b-47a9-9760-457222ec1c82.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alle producten\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u2744 Dorade royalefilet met vel 120-160g 5kg DV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\",\"name\":\"Seaco\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2744 Dorade royalefilet met vel 120-160g 5kg DV - Seaco","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"\u2744 Dorade royalefilet met vel 120-160g 5kg DV - Seaco","og_description":"Filet van dorade royale met huid en zonder graatje, sortering 120 tot 160g, bevroren en verpakt per doos van 5kg.","og_url":"https:\/\/www.onestep.media\/seaco\/product\/\u2744-dorade-royalefilet-met-vel-120-160g-5kg-dv\/","og_site_name":"Seaco","article_modified_time":"2026-04-27T18:41:28+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/","url":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/","name":"\u2744 Dorade royalefilet met vel 120-160g 5kg DV - Seaco","isPartOf":{"@id":"https:\/\/www.onestep.media\/seaco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/#primaryimage"},"image":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-50925ac8-292b-47a9-9760-457222ec1c82.jpg","datePublished":"2026-04-27T18:05:23+00:00","dateModified":"2026-04-27T18:41:28+00:00","breadcrumb":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/#primaryimage","url":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-50925ac8-292b-47a9-9760-457222ec1c82.jpg","contentUrl":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-50925ac8-292b-47a9-9760-457222ec1c82.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-dorade-royalefilet-met-vel-120-160g-5kg-dv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.onestep.media\/seaco\/"},{"@type":"ListItem","position":2,"name":"Alle producten","item":"https:\/\/www.onestep.media\/seaco\/winkel\/"},{"@type":"ListItem","position":3,"name":"\u2744 Dorade royalefilet met vel 120-160g 5kg DV"}]},{"@type":"WebSite","@id":"https:\/\/www.onestep.media\/seaco\/#website","url":"https:\/\/www.onestep.media\/seaco\/","name":"Seaco","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onestep.media\/seaco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product\/3329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/comments?post=3329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/media\/2247"}],"wp:attachment":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/media?parent=3329"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_brand?post=3329"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_cat?post=3329"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_tag?post=3329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}