{"id":3433,"date":"2026-04-27T19:05:58","date_gmt":"2026-04-27T18:05:58","guid":{"rendered":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/"},"modified":"2026-04-27T19:41:45","modified_gmt":"2026-04-27T18:41:45","slug":"%e2%9d%84-edamame-sojabonen-1kg","status":"publish","type":"product","link":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/","title":{"rendered":"\u2744 Edamame sojabonen 1kg"},"content":{"rendered":"<p>Edamame zijn onrijpe sojaboontjes in de peul. Rijk aan vitaminen (A en C), ijzer, eiwitten, omega-3-vetzuren, calcium en vezels. En ook nog laag in calorische waarde.<\/p>\n<p>Onmisbaar in de Aziatische (in het bijzonder de Japanse) keuken en ook ontdekt door vegetari\u00ebrs en veganisten.<\/p>\n<p>Eet ze als snack of verwerk ze in pok\u00e9bowl of salade. Ze passen (zonder peul) ook uitstekend in een gerecht. Combineer bijvoorbeeld met kabeljauw in misoboter en sesam met bimi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sojabonen met schil, bevroren in zakken van 1kg.<\/p>\n","protected":false},"featured_media":2035,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[186,189],"product_tag":[],"class_list":{"0":"post-3433","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-overige-visproducten","7":"product_cat-zeegroenten-wieren","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2744 Edamame sojabonen 1kg - Seaco<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2744 Edamame sojabonen 1kg - Seaco\" \/>\n<meta property=\"og:description\" content=\"Sojabonen met schil, bevroren in zakken van 1kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onestep.media\/seaco\/product\/\u2744-edamame-sojabonen-1kg\/\" \/>\n<meta property=\"og:site_name\" content=\"Seaco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T18:41:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/\",\"name\":\"\u2744 Edamame sojabonen 1kg - Seaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-e41ba59e-8303-45b5-8f9d-7e162e555343.jpg\",\"datePublished\":\"2026-04-27T18:05:58+00:00\",\"dateModified\":\"2026-04-27T18:41:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-e41ba59e-8303-45b5-8f9d-7e162e555343.jpg\",\"contentUrl\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-e41ba59e-8303-45b5-8f9d-7e162e555343.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/%e2%9d%84-edamame-sojabonen-1kg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alle producten\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u2744 Edamame sojabonen 1kg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\",\"name\":\"Seaco\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2744 Edamame sojabonen 1kg - Seaco","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"\u2744 Edamame sojabonen 1kg - Seaco","og_description":"Sojabonen met schil, bevroren in zakken van 1kg.","og_url":"https:\/\/www.onestep.media\/seaco\/product\/\u2744-edamame-sojabonen-1kg\/","og_site_name":"Seaco","article_modified_time":"2026-04-27T18:41:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/","url":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/","name":"\u2744 Edamame sojabonen 1kg - Seaco","isPartOf":{"@id":"https:\/\/www.onestep.media\/seaco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/#primaryimage"},"image":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-e41ba59e-8303-45b5-8f9d-7e162e555343.jpg","datePublished":"2026-04-27T18:05:58+00:00","dateModified":"2026-04-27T18:41:45+00:00","breadcrumb":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/#primaryimage","url":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-e41ba59e-8303-45b5-8f9d-7e162e555343.jpg","contentUrl":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-e41ba59e-8303-45b5-8f9d-7e162e555343.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.onestep.media\/seaco\/product\/%e2%9d%84-edamame-sojabonen-1kg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.onestep.media\/seaco\/"},{"@type":"ListItem","position":2,"name":"Alle producten","item":"https:\/\/www.onestep.media\/seaco\/winkel\/"},{"@type":"ListItem","position":3,"name":"\u2744 Edamame sojabonen 1kg"}]},{"@type":"WebSite","@id":"https:\/\/www.onestep.media\/seaco\/#website","url":"https:\/\/www.onestep.media\/seaco\/","name":"Seaco","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onestep.media\/seaco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product\/3433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/comments?post=3433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/media\/2035"}],"wp:attachment":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/media?parent=3433"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_brand?post=3433"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_cat?post=3433"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_tag?post=3433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}