{"id":3548,"date":"2026-04-27T19:06:36","date_gmt":"2026-04-27T18:06:36","guid":{"rendered":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/"},"modified":"2026-04-27T19:42:01","modified_gmt":"2026-04-27T18:42:01","slug":"zeebaarsfilet-met-vel-140-180g-600-800","status":"publish","type":"product","link":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/","title":{"rendered":"Zeebaarsfilet met vel 140-180g (600-800)"},"content":{"rendered":"<p>De (Europees) zeebaars, moeder van de baarsachtigen, wordt veel gekweekt in de Middellandse Zee, vooral in Turkije en Griekenland. Het is een zeer gewaarde vis vanwege zijn stevigheid, sappigheid en heerlijk milde smaak.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zeebaarsfilet met huid, sortering 140 tot 180g.<\/p>\n","protected":false},"featured_media":2086,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[169],"product_tag":[],"class_list":{"0":"post-3548","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-filet-portie","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zeebaarsfilet met vel 140-180g (600-800) - Seaco<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeebaarsfilet met vel 140-180g (600-800) - Seaco\" \/>\n<meta property=\"og:description\" content=\"Zeebaarsfilet met huid, sortering 140 tot 180g.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/\" \/>\n<meta property=\"og:site_name\" content=\"Seaco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T18:42:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/\",\"name\":\"Zeebaarsfilet met vel 140-180g (600-800) - Seaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-709289eb-3719-42ed-a7a5-6cb5d2e4e0fd.jpg\",\"datePublished\":\"2026-04-27T18:06:36+00:00\",\"dateModified\":\"2026-04-27T18:42:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-709289eb-3719-42ed-a7a5-6cb5d2e4e0fd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/reflex-article-709289eb-3719-42ed-a7a5-6cb5d2e4e0fd.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product\\\/zeebaarsfilet-met-vel-140-180g-600-800\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alle producten\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zeebaarsfilet met vel 140-180g (600-800)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\",\"name\":\"Seaco\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zeebaarsfilet met vel 140-180g (600-800) - Seaco","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"Zeebaarsfilet met vel 140-180g (600-800) - Seaco","og_description":"Zeebaarsfilet met huid, sortering 140 tot 180g.","og_url":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/","og_site_name":"Seaco","article_modified_time":"2026-04-27T18:42:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/","url":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/","name":"Zeebaarsfilet met vel 140-180g (600-800) - Seaco","isPartOf":{"@id":"https:\/\/www.onestep.media\/seaco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/#primaryimage"},"image":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-709289eb-3719-42ed-a7a5-6cb5d2e4e0fd.jpg","datePublished":"2026-04-27T18:06:36+00:00","dateModified":"2026-04-27T18:42:01+00:00","breadcrumb":{"@id":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/#primaryimage","url":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-709289eb-3719-42ed-a7a5-6cb5d2e4e0fd.jpg","contentUrl":"https:\/\/www.onestep.media\/seaco\/wp-content\/uploads\/2026\/02\/reflex-article-709289eb-3719-42ed-a7a5-6cb5d2e4e0fd.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.onestep.media\/seaco\/product\/zeebaarsfilet-met-vel-140-180g-600-800\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.onestep.media\/seaco\/"},{"@type":"ListItem","position":2,"name":"Alle producten","item":"https:\/\/www.onestep.media\/seaco\/winkel\/"},{"@type":"ListItem","position":3,"name":"Zeebaarsfilet met vel 140-180g (600-800)"}]},{"@type":"WebSite","@id":"https:\/\/www.onestep.media\/seaco\/#website","url":"https:\/\/www.onestep.media\/seaco\/","name":"Seaco","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onestep.media\/seaco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product\/3548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/comments?post=3548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/media\/2086"}],"wp:attachment":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/media?parent=3548"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_brand?post=3548"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_cat?post=3548"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_tag?post=3548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}