{"id":189,"count":5,"description":"","link":"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/zeegroenten-wieren\/","name":"Zeegroenten &amp; Wieren","slug":"zeegroenten-wieren","taxonomy":"product_cat","parent":196,"meta":[],"menu_order":29,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zeegroenten &amp; Wieren Archieven - Seaco<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeegroenten &amp; Wieren Archieven - Seaco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/zeegroenten-wieren\/\" \/>\n<meta property=\"og:site_name\" content=\"Seaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product-categorie\\\/diversen\\\/zeegroenten-wieren\\\/\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product-categorie\\\/diversen\\\/zeegroenten-wieren\\\/\",\"name\":\"Zeegroenten &amp; Wieren Archieven - Seaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product-categorie\\\/diversen\\\/zeegroenten-wieren\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product-categorie\\\/diversen\\\/zeegroenten-wieren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diversen\",\"item\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/product-categorie\\\/diversen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zeegroenten &amp; Wieren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/#website\",\"url\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/\",\"name\":\"Seaco\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.onestep.media\\\/seaco\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zeegroenten &amp; Wieren Archieven - Seaco","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"Zeegroenten &amp; Wieren Archieven - Seaco","og_url":"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/zeegroenten-wieren\/","og_site_name":"Seaco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/zeegroenten-wieren\/","url":"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/zeegroenten-wieren\/","name":"Zeegroenten &amp; Wieren Archieven - Seaco","isPartOf":{"@id":"https:\/\/www.onestep.media\/seaco\/#website"},"breadcrumb":{"@id":"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/zeegroenten-wieren\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/zeegroenten-wieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.onestep.media\/seaco\/"},{"@type":"ListItem","position":2,"name":"Diversen","item":"https:\/\/www.onestep.media\/seaco\/product-categorie\/diversen\/"},{"@type":"ListItem","position":3,"name":"Zeegroenten &amp; Wieren"}]},{"@type":"WebSite","@id":"https:\/\/www.onestep.media\/seaco\/#website","url":"https:\/\/www.onestep.media\/seaco\/","name":"Seaco","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onestep.media\/seaco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_cat\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product_cat\/196"}],"wp:post_type":[{"href":"https:\/\/www.onestep.media\/seaco\/wp-json\/wp\/v2\/product?product_cat=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}